{"id":125143,"date":"2026-04-19T20:20:48","date_gmt":"2026-04-19T13:20:48","guid":{"rendered":"https:\/\/missav.plus\/mky-ba-004-sub-tailandes-wu-mengmeng\/"},"modified":"2026-04-19T20:35:24","modified_gmt":"2026-04-19T13:35:24","slug":"mky-ba-004-sub-tailandes-wu-mengmeng","status":"publish","type":"post","link":"https:\/\/njavtv.me\/pt-br\/mky-ba-004-sub-tailandes-wu-mengmeng\/","title":{"rendered":"Filme x Legenda Tailandesa MKY-BA-004 Evento Especial P\u00f3s-Escola Wu Mengmeng"},"content":{"rendered":"<p>Filme x Legenda Tailandesa MKY-BA-004 Trabalho Especial Ap\u00f3s a Escola Wu Mengmeng Uma jovem precisa encontrar um emprego depois da escola para pagar as mensalidades escolares Ela se recusava a sair com as amigas porque n\u00e3o tinha dinheiro, mas hoje a sorte caiu com ela. Quando o jovem Hiso a contatou pela linha que havia se registrado para o trabalho, ela ficou chocada. Ofereceram 100.000 yuans em troca de sexo com ela em uniforme escolar. Ela n\u00e3o teve escolha, ent\u00e3o aceitou o emprego porque queria mudar seu futuro.<br \/>\n<iframe loading=\"lazy\" class=\"videowrapper\" src=\"https:\/\/fembeqv2.xyz\/player\/index.php?data=82356b37a12462391abf004c8362d389\" width=\"300\" height=\"175\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Filme x Legenda Tailandesa MKY-BA-004 Trabalho Especial Ap\u00f3s a Escola Wu Mengmeng Uma jovem precisa encontrar um emprego depois da escola para pagar as mensalidades escolares Ela se recusava a sair com as amigas porque n\u00e3o tinha dinheiro, mas hoje a sorte caiu com ela. Quando o jovem Hiso a contatou pela linha que havia [&#8230;]<\/p>\n<p><a class=\"btn btn-primary wpst-read-more-link\" href=\"https:\/\/njavtv.me\/pt-br\/mky-ba-004-sub-tailandes-wu-mengmeng\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":2,"featured_media":125001,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12560,12486,12329,12406],"tags":[34701,13052,12902,14549,12489,29194,13347],"actors":[21228],"class_list":["post-125143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-av-chines","category-av-subthai-pt-br","category-av-uncen-pt-br","category-novo-av","tag-fantasia","tag-garota-sideline","tag-mky-pt-br","tag-peitos-agradaveis","tag-rachadura","tag-sub-tailandes","tag-uniforme-escolar","actors-wu-mengmeng-pt-br"],"_links":{"self":[{"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/posts\/125143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/comments?post=125143"}],"version-history":[{"count":0,"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/posts\/125143\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/media\/125001"}],"wp:attachment":[{"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/media?parent=125143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/categories?post=125143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/tags?post=125143"},{"taxonomy":"actors","embeddable":true,"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/actors?post=125143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}