{"id":72994,"date":"2024-11-21T04:22:00","date_gmt":"2024-11-20T21:22:00","guid":{"rendered":"https:\/\/missav.plus\/stars-794-ataque-a-casa-do-estudante-mei-miyajima\/"},"modified":"2024-11-23T16:03:43","modified_gmt":"2024-11-23T09:03:43","slug":"stars-794-ataque-a-casa-do-estudante-mei-miyajima","status":"publish","type":"post","link":"https:\/\/njavtv.me\/pt-br\/stars-794-ataque-a-casa-do-estudante-mei-miyajima\/","title":{"rendered":"STARS-794 Ataque \u00e0 casa do estudante Mei Miyajima"},"content":{"rendered":"<p>STARS-794 [Sem censura] Ataque a um estudante em casa Mei Miyajima Sinopse Ela desempenha o papel de uma tutora que tem que ensinar um aluno por quem ela j\u00e1 tem uma queda. Quando ela teve a oportunidade de estar juntos 2 contra 2, ela conseguiu atac\u00e1-lo.<br \/>\n<iframe loading=\"lazy\" class=\"videowrapper\" src=\"https:\/\/fembeqq.xyz\/player\/index.php?data=3eebabe3234038516503146e19191ac5\" width=\"300\" height=\"175\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>STARS-794 [Sem censura] Ataque a um estudante em casa Mei Miyajima Sinopse Ela desempenha o papel de uma tutora que tem que ensinar um aluno por quem ela j\u00e1 tem uma queda. Quando ela teve a oportunidade de estar juntos 2 contra 2, ela conseguiu atac\u00e1-lo. [&#8230;]<\/p>\n<p><a class=\"btn btn-primary wpst-read-more-link\" href=\"https:\/\/njavtv.me\/pt-br\/stars-794-ataque-a-casa-do-estudante-mei-miyajima\/\">Read More&#8230;<\/a><\/p>\n","protected":false},"author":4,"featured_media":72983,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12326,12329,12327],"tags":[21739,12647,12846,26943,12421,12945],"actors":[12653],"class_list":["post-72994","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-av-japao","category-av-uncen-pt-br","category-professor-aluno-av","tag-copo-f","tag-estrelas","tag-menina-de-cabelo-curto","tag-minissaia","tag-peitos-grandes","tag-tutor-pt-br-2","actors-mei-miyajima-pt-br"],"_links":{"self":[{"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/posts\/72994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/comments?post=72994"}],"version-history":[{"count":0,"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/posts\/72994\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/media\/72983"}],"wp:attachment":[{"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/media?parent=72994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/categories?post=72994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/tags?post=72994"},{"taxonomy":"actors","embeddable":true,"href":"https:\/\/njavtv.me\/pt-br\/wp-json\/wp\/v2\/actors?post=72994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}